{"id":86972,"date":"2025-03-28T12:48:10","date_gmt":"2025-03-28T11:48:10","guid":{"rendered":"https:\/\/www.irta.cat\/?post_type=noticia&#038;p=86972"},"modified":"2026-03-27T13:54:02","modified_gmt":"2026-03-27T12:54:02","slug":"entrevista-jaume-casadesus-agua-cataluna","status":"publish","type":"noticia","link":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/","title":{"rendered":"Jaume Casades\u00fas: \u201cEn el caso del agua en Catalu\u00f1a, la gobernanza colectiva es el camino\u201d"},"content":{"rendered":"\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre.jpg\" class=\"fancybox irta-lightbox-bridge\" data-fancybox=\"irta-images\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"669\" src=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre.jpg\" alt=\"Jaume Casades\u00fas\" class=\"wp-image-86764\" srcset=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre.jpg 1000w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre-300x201.jpg 300w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre-768x514.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption class=\"wp-element-caption\">Jaume Casades\u00fas, en la terraza del IRTA Fruitcentre, con la llanura de L\u00e9rida al fondo.<\/figcaption><\/figure>\n\n\n\n<p class=\"has-background wp-block-paragraph\" style=\"background-color:#fff1ca\">Bi\u00f3logo doctorado en Fisiolog\u00eda vegetal, e Ingeniero inform\u00e1tico, <a href=\"https:\/\/www.irta.cat\/es\/personal\/jaume-casadesus\/\">Jaume Casades\u00fas<\/a> es el jefe del <a href=\"https:\/\/www.irta.cat\/es\/programa-de-recerca\/uso-eficiente-del-agua-en-agricultura\/\">programa de Uso eficiente del agua en la agricultura<\/a> del IRTA (Instituto de Investigaci\u00f3n y Tecnolog\u00eda Agroalimentarias). Profundo conocedor de las necesidades de las personas que riegan los campos de cultivo catalanes, en primavera de 2023 vivi\u00f3 desde primera l\u00ednea la situaci\u00f3n de extrema sequ\u00eda, y tiene claro cu\u00e1l es el camino para estar m\u00e1s preparados cuando la escasez de agua regrese, porque va a regresar. Nos lo cuenta en esta entrevista, donde tambi\u00e9n revela otras curiosidades de su carrera profesional, como por ejemplo su conocimiento sobre los campos ucranianos afectados por el accidente nuclear de Chern\u00f3byl de 1986.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hace poco menos de una semana, se celebr\u00f3 el d\u00eda Mundial del Agua, bajo el lema <a href=\"https:\/\/www.un.org\/en\/observances\/water-day\" target=\"_blank\" rel=\"noreferrer noopener\">Salvemos nuestros g<\/a><a href=\"https:\/\/www.un.org\/en\/observances\/water-day\">laciares<\/a>. Los grandes glaciares de la Tierra pierden hielo y <a href=\"https:\/\/efeverde.com\/glaciares-del-pirineo-un-paisaje-unico-condenado-a-desaparecer\/\" target=\"_blank\" rel=\"noreferrer noopener\">los del Pirineo, mucho m\u00e1s peque\u00f1os, tambi\u00e9n<\/a>.<\/strong><br>Que los glaciares del Pirineo o los grandes glaciares de la Tierra se derritan es un indicador de que las temperaturas medias de los veranos est\u00e1n subiendo. Esto se puede registrar, nunca hab\u00edan estado en estos m\u00ednimos y debemos actuar. Es una alerta dif\u00edcil de contradecir. Precisamente, los primeros indicios del cambio clim\u00e1tico se declararon a ra\u00edz de la observaci\u00f3n de los glaciares de la Ant\u00e1rtida. Si bien en Catalu\u00f1a no estamos conectados con el ciclo del agua de estos grandes glaciares, que se est\u00e9n derritiendo demuestra que no podemos negar el cambio clim\u00e1tico.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En Catalu\u00f1a, la noticia clim\u00e1tica de los \u00faltimos d\u00edas es la lluvia, que est\u00e1 rellenando los <a href=\"https:\/\/aca.gencat.cat\/ca\/laigua\/estat-del-medi-hidric\/recursos-disponibles\/estat-de-les-reserves-daigua-als-embassaments\/\" target=\"_blank\" rel=\"noreferrer noopener\">embalses<\/a>. \u00bfPueden los agricultores respirar m\u00e1s tranquilos?<\/strong><br>M\u00e1s que hace un a\u00f1o, seguro que s\u00ed. Pero depende de d\u00f3nde est\u00e9n situados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfDebemos dividir Catalu\u00f1a en dos partes, verdad?<\/strong><br>Una mitad corresponde al oeste: la cuenca del Ebro, b\u00e1sicamente L\u00e9rida y parte de Tarragona. Es un \u00e1rea poco poblada, donde la actividad agr\u00edcola tiene bastante peso. Esta mitad de Catalu\u00f1a se abastece, sobre todo, de agua del Ebro o de sus afluentes. Hay bastante agua y bastantes embalses. En esta parte no deber\u00eda ser habitual que haya problemas de abastecimiento, los cuales, durante la sequ\u00eda de 2023, estuvieron relacionados con la gesti\u00f3n que se estaba realizando, no solo con cuestiones clim\u00e1ticas. Hoy, podemos respirar bastante tranquilos. Hay reservas y queda nieve por fundirse. Por ello, incluso se deja correr el agua de los embalses en previsi\u00f3n de que llegue m\u00e1s, procedente del deshielo. Pero siempre tenemos que estar atentos, porque las reservas deben rellenarse cada a\u00f1o.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00bf<strong>Y en la parte del este?<\/strong><br>En esta parte, las cuencas internas catalanas, el riego se abastece de una combinaci\u00f3n m\u00e1s variada de recursos h\u00eddricos, diferentes seg\u00fan la zona, en la que entran en juego tanto el agua superficial, como la de acu\u00edferos como, en alg\u00fan lugar concreto, tambi\u00e9n el agua regenerada de depuradora. Las cuencas internas disponen de menos del 40% del volumen de agua de Catalu\u00f1a, hay menos embalses y de menor capacidad, pero, en cambio, en esa parte del territorio vive m\u00e1s del 90% de la poblaci\u00f3n, la cual crece, y existe una actividad econ\u00f3mica muy din\u00e1mica. La situaci\u00f3n es de escasez cr\u00f3nica. Con la lluvia reciente respiramos un poco m\u00e1s tranquilos, pero necesitamos alargar el uso de esta agua que ahora cae, porque no sabemos hasta cu\u00e1ndo tendremos que fiarnos de ella. En el IRTA, nos fijamos en los agricultores y estudiamos c\u00f3mo podemos afinar al m\u00e1ximo la eficiencia en el uso del agua tanto en la cuenca del Ebro como en las cuencas internas.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/PAG-21-min-scaled.jpg\" class=\"fancybox irta-lightbox-bridge\" data-fancybox=\"irta-images\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/PAG-21-min-1024x768.jpg\" alt=\"Un vehicle de l\u2019IRTA de cam\u00ed cap a assajos de camp, a Ra\u00efmat.\" class=\"wp-image-86903\" srcset=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/PAG-21-min-1024x768.jpg 1024w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/PAG-21-min-300x225.jpg 300w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/PAG-21-min-768x576.jpg 768w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/PAG-21-min-1536x1152.jpg 1536w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/PAG-21-min-2048x1536.jpg 2048w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/PAG-21-min-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Un veh\u00edculo del IRTA en direcci\u00f3n a los ensayos de campo en Ra\u00efmat.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 cultivos o productores son los que m\u00e1s est\u00e1n sufriendo, en el actual contexto de cambio clim\u00e1tico?<\/strong><br>Los de las comarcas del Alt Empord\u00e0, el Priorat y el Baix Camp, donde la falta de agua est\u00e1 muy cronificada. En el Pened\u00e8s, que t\u00edpicamente era de secano, han tenido un episodio de varios a\u00f1os seguidos de poca pluviometr\u00eda, pero no sabemos si en el futuro la lluvia volver\u00e1 a la normalidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQui\u00e9n decide cu\u00e1ndo y cu\u00e1nto se riega?<\/strong><br>Cuando se trata de agua superficial, la de los r\u00edos o embalses, los agricultores suelen estar organizados en comunidades de regantes, que gestionan su distribuci\u00f3n. Por otro lado, en el caso de los acu\u00edferos, hist\u00f3ricamente los campesinos abr\u00edan un pozo y cada uno iba por su lado, pero ahora estamos viendo que el agua es un recurso finito: si uno saca m\u00e1s agua de su pozo, quiz\u00e1s el otro se queda sin. Por eso, hace diez a\u00f1os empezaron a aparecer las Juntas de usuarios de agua. La primera fue la del Baix Ter, un caso de \u00e9xito, y despu\u00e9s se han ido creando otras. Estas juntas agrupan a todos los usuarios: los agricultores, pero tambi\u00e9n los municipios y la industria. Los municipios tienen mayor capacidad de aportar recursos econ\u00f3micos y profesionales t\u00e9cnicos. Todos gestionan el agua de forma sensata porque todos est\u00e1n en el mismo barco y nadie quiere quedarse sin ella. Desde el IRTA, consideramos que es una f\u00f3rmula que tiene mucho valor.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hay mucho margen de mejora en el uso del agua para el riego, \u00bfverdad?<\/strong><br>S\u00ed, vamos con retraso. Uno de los principales motivos son las infraestructuras antiguas. Por ejemplo, en Ponent, la zona oeste, hace 150 a\u00f1os el sistema de riego de los Canales de Urgell fue muy moderno, muy innovador. En aquellos momentos, la \u00fanica forma de regar era por inundaci\u00f3n, pero ahora esto ya no es eficiente y tenemos m\u00e1s tecnolog\u00edas y tambi\u00e9n posibilidades distintas de cultivar. Ahora es necesario que el agua llegue presurizada a las parcelas y no a trav\u00e9s de canales abiertos.  <\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-black-color has-text-color has-link-color wp-elements-1\"><em>\u201cPara modernizar las infraestructuras de riego, es necesario que el agua llegue presurizada a las parcelas y no a trav\u00e9s de canales abiertos\u00bb<\/em><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfCanalizar el agua de los r\u00edos?<\/strong><br>S\u00ed. La que procede de pozos ya llega presurizada. Pero la que procede de r\u00edos, en muchas zonas llega a las parcelas a trav\u00e9s de acequias abiertas, muchas de las cuales tienen p\u00e9rdidas. Y, en muchos casos, despu\u00e9s los campos se riegan por inundaci\u00f3n, lo que es muy poco eficiente. En cambio, si se utiliza un sistema de distribuci\u00f3n de agua presurizada, con tuber\u00edas, y dentro de la finca se reparte con aspersores o por goteo, el agua se convierte en cosecha m\u00e1s eficientemente: pierdes menos agua y puedes controlar cu\u00e1ndo riegas y durante cu\u00e1nto tiempo. En per\u00edodos de sequ\u00eda, quienes  riegan por inundaci\u00f3n son m\u00e1s fr\u00e1giles porque no tienen margen de maniobra. En este sentido, en la llanura de L\u00e9rida hay bastantes deberes pendientes, y se habla mucho de ello, pero tambi\u00e9n en Gerona tienen deberes. Se est\u00e1 trabajando a ambos lados. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfPor qu\u00e9 vamos con retraso?<\/strong><br>Porque muchos de estos canales se construyeron a iniciativa privada, pero ahora no se puede cargar todo el peso de su modernizaci\u00f3n sobre los agricultores: que tengan que hacer una inversi\u00f3n de mejora para gastar menos agua con tal de que la aprovechemos todos, no es un gran est\u00edmulo para ellos, y m\u00e1s teniendo en cuenta que muchos propietarios no son agricultores en activo, sino que alquilan los terrenos a otras personas. Debemos pensar en c\u00f3mo solucionarlo, y mientras tanto la modernizaci\u00f3n se ha retrasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo debe llegar esta soluci\u00f3n?<\/strong><br>Con el entendimiento entre las administraciones y los agricultores. Sobre todo, es imprescindible que los agricultores puedan confiar plenamente en el retorno de sus inversiones.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfY el famoso trasvase del agua del Ebro hacia la Catalu\u00f1a del este podr\u00eda ser tambi\u00e9n una soluci\u00f3n?<\/strong><br>Podr\u00eda serlo, por supuesto, pero no me corresponde a m\u00ed decirlo, porque es una cuesti\u00f3n que debe resolverse pol\u00edticamente, no t\u00e9cnicamente.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>En el IRTA trabajamos en la gesti\u00f3n del agua para usos agr\u00edcolas desde que la organizaci\u00f3n naci\u00f3, hace cuatro d\u00e9cadas. Esto nos ha permitido conocer muy bien las necesidades de las plantas y de la tierra al tiempo que desarrollar tecnolog\u00edas que eran ciencia ficci\u00f3n hace muy poco tiempo. \u00bfEn qu\u00e9 enfoc\u00e1is vuestro trabajo, actualmente?<\/strong><br>Si a\u00f1os atr\u00e1s quiz\u00e1s nos focaliz\u00e1bamos m\u00e1s en los m\u00e9todos de riego m\u00e1s punteros, y por tanto trabaj\u00e1bamos sobre todo con las explotaciones agr\u00edcolas m\u00e1s abiertas y capacitadas para innovar, hoy tenemos una mirada m\u00e1s hol\u00edstica y no queremos dejarnos a nadie ni fijarnos \u00fanicamente en el riego. Es decir, para mejorar el uso del agua en la agricultura, no debemos velar solo por la dosificaci\u00f3n del riego. Tambi\u00e9n debemos tener en cuenta otras cuestiones: una, la gesti\u00f3n de los suelos; la otra, el sistema de poda o de plantaci\u00f3n, que hace que un cultivo sea m\u00e1s o menos vulnerable a la sequ\u00eda o que necesite m\u00e1s o menos agua. Y, adem\u00e1s, debemos tener en cuenta que no en todas partes se puede hacer lo mismo porque no en todas partes existe la misma cantidad ni calidad de agua. Por eso, tambi\u00e9n estudiamos el uso del agua regenerada de depuradoras para el riego, a la vez que estamos implantando <a href=\"https:\/\/www.irta.cat\/es\/noticia\/regassist-la-red-de-asistencia-al-riego-para-optimizar-el-uso-del-agua-en-cataluna\/\">una red de t\u00e9cnicas en todo el territorio catal\u00e1n que asesoran a los regantes<\/a>.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center has-black-color has-text-color has-link-color wp-elements-2\"><em>\u201cAntes nos focaliz\u00e1bamos en los m\u00e9todos de riego m\u00e1s punteros, mientras que hoy tenemos una mirada m\u00e1s hol\u00edstica y no queremos dejarnos a nadie\u201d<\/em><\/h3>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>El IRTA ha destacado mucho por la implantaci\u00f3n de nuevas tecnolog\u00edas en el riego.<\/strong><br>Actualmente, trabajamos sobre todo con los gemelos digitales. Son r\u00e9plicas virtuales de las parcelas, que nos permiten estudiar qu\u00e9 ocurre en cada finca y qu\u00e9 necesidades tendr\u00e1 en las semanas y meses futuros. Gracias a los sensores que instalamos en las parcelas, o tambi\u00e9n por teledetecci\u00f3n por sat\u00e9lite, podemos saber qu\u00e9 est\u00e1 pasando: cu\u00e1nta agua se est\u00e1 aplicando, cu\u00e1l es la humedad del suelo, qu\u00e9 cultivos hay, y si han crecido m\u00e1s o menos. As\u00ed podemos saber si necesitan m\u00e1s agua o la necesitar\u00e1n m\u00e1s adelante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>(\u2026)<\/strong><br>Adem\u00e1s, relacionamos todas estas observaciones con modelos digitales que simulan c\u00f3mo crece el cultivo o c\u00f3mo se mueve el agua. Y esto es lo que nos permite saber qu\u00e9 va a pasar dentro de una semana o dentro de dos meses. Los gemelos los estamos implementando a tres niveles: primero, en fincas individuales, mediante un sistema que ya hemos transferido a una empresa que lo comercializa internacionalmente; segundo, en territorios grandes, como el Baix Ter o el Pla de Lleida, lo que nos sirvi\u00f3 mucho en situaci\u00f3n de sequ\u00eda, y, tercero, en la gesti\u00f3n de las comunidades de regantes. Esta tercera opci\u00f3n tiene mucho \u00e9xito, porque las comunidades de regantes deben solicitar el agua a quien gestiona los embalses, y con los gemelos digitales pueden saber cu\u00e1nta agua tienen actualmente y explicar a los regantes c\u00f3mo dosificarla, y adem\u00e1s pueden prever cu\u00e1nta agua pedir\u00e1n entre todos la pr\u00f3xima semana para no pasarse ni quedarse cortos.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><a href=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/IRTA-tecnologies-reg.jpg\" class=\"fancybox irta-lightbox-bridge\" data-fancybox=\"irta-images\"><img loading=\"lazy\" decoding=\"async\" width=\"1000\" height=\"749\" src=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/IRTA-tecnologies-reg.jpg\" alt=\"Sistema de mesura de fluxos d\u2019aigua i CO2 per validar teledetecci\u00f3, en una finca de Maials.\" class=\"wp-image-86792\" srcset=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/IRTA-tecnologies-reg.jpg 1000w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/IRTA-tecnologies-reg-300x225.jpg 300w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/IRTA-tecnologies-reg-768x575.jpg 768w\" sizes=\"auto, (max-width: 1000px) 100vw, 1000px\" \/><\/a><figcaption class=\"wp-element-caption\">Sistema de medici\u00f3n de flujos de agua y CO2 per validar teledetecci\u00f3n, en una finca de Maials.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Todo este trabajo lo hac\u00e9is conectados internacionalmente, \u00bfverdad?<\/strong><br>Tradicionalmente, hemos estado muy conectados con la <a href=\"http:\/\/Todo este trabajo lo hizo conectados internacionalmente, \u00bfverdad? Tradicionalmente, hemos estado muy conectados con la Universidad de Davis, en California, donde tambi\u00e9n poseen un clima Mediterr\u00e1neo, y trabajamos con grupos de investigaci\u00f3n de todo el arco Mediterr\u00e1neo, adem\u00e1s de Sud\u00e1frica, Australia, Chile o Argentina, que tambi\u00e9n tienen el mismo clima. Pero, de hecho, en Catalu\u00f1a y el resto de Espa\u00f1a podemos sacar pecho porque probablemente somos quienes hacemos una investigaci\u00f3n m\u00e1s avanzada en gesti\u00f3n del agua, con la particularidad de que mucha de esta gesti\u00f3n es colectiva y p\u00fablica.  Llegaste al IRTA hace m\u00e1s de dos d\u00e9cadas. \u00bfQu\u00e9 te trajo? Mi recorrido no es habitual. Despu\u00e9s de la carrera y el doctorado, no hice ning\u00fan postdoc, sino que trabaj\u00e9 cinco a\u00f1os como t\u00e9cnico en los campos experimentales de la Universidad de Barcelona. Esto me permiti\u00f3 formar parte de varios grupos de investigaci\u00f3n a la vez. Todos ten\u00edan en com\u00fan que hac\u00edan trabajo de campo y necesitaban tecnolog\u00edas para su investigaci\u00f3n: instrumentaci\u00f3n, simulaciones, sens\u00f3rica\u2026 Pues \u00e9ste, m\u00e1s que el agua, ha sido el hilo conductor de mi recorrido profesional. Podr\u00edamos decir que me he ido especializando en la digitalizaci\u00f3n en el campo. Y, en ese momento, acab\u00e9 trabajando en un tema sobre Chernobyl.  \u00bfNos lo cuentas? A finales de los noventa, se hac\u00edan muchos proyectos sobre c\u00f3mo solucionar los problemas que hab\u00eda en las zonas contaminadas por ese accidente nuclear, y sobre cu\u00e1l deber\u00eda ser el plan de contingencia si esto ocurriera en Europa occidental. Yo, concretamente, trabaj\u00e9 en dos proyectos europeos para estudiar c\u00f3mo los contaminantes pasaban del suelo a la ra\u00edz. Pues lo hicimos tan bien que el problema acab\u00f3.  \u00bfDe qu\u00e9 forma? Parec\u00eda que ese accidente representar\u00eda un problema durante mucho tiempo, que las zonas afectadas de Ucrania y Bielorrusia quedar\u00edan contaminadas durante siglos. \u00a1Pues ahora estamos importante grano de esas zonas! Una de las conclusiones de esos proyectos fue que la situaci\u00f3n se hab\u00eda estabilizado mucho m\u00e1s r\u00e1pido de lo que pens\u00e1bamos. Los contaminantes quedaron enganchados a las arcillas del suelo y, aunque sigan all\u00ed, no pasan a los cultivos. \u00a1Fue una sorpresa positiva que nos dej\u00f3 sin trabajo! Tuve que reciclarme, y lo hice hacia el IRTA.  (\u2026) Primero, me dediqu\u00e9 a la digitalizaci\u00f3n de la horticultura intensiva del Maresme, pero en aquella \u00e9poca, los invernaderos se vend\u00edan para crecer urban\u00edsticamente, as\u00ed que el trabajo no ten\u00eda demasiado futuro. Y termin\u00e9 en Lleida, aqu\u00ed, en el Fruitcentre, trabajando en temas de agua.  \u00bfQu\u00e9 es lo m\u00e1s gratificante de tu trabajo? Que no s\u00f3lo hacemos burbujas en una pecera, sino que vayamos a jugar con fuego real en una trinchera. Y eso, si lo sales, es gratificante.  \u00bfNos pones un ejemplo? En 2023, en el IRTA estuvimos en el ojo del hurac\u00e1n ante la crisis de la sequ\u00eda. Varios sectores se peleaban ya nosotros nos situaron de mediador. En Lleida, el conflicto fue entre comunidades de regantes que se disputaban el mismo embalse, y en Girona fue entre el abastecimiento urbano y el de la agricultura. Fueron dos batallas distintas en paralelo. Tuvimos la suerte de que la situaci\u00f3n se afloj\u00f3, pero realmente era inevitable que hubiera un mediador. Que nos situaran a nosotros en ese papel fue intenso, muy arriesgado, pero tambi\u00e9n muy motivador. Fue un reconocimiento.\" target=\"_blank\" rel=\"noreferrer noopener\">Universidad de Davis<\/a>, en California, donde tambi\u00e9n tienen un clima Mediterr\u00e1neo, y trabajamos con grupos de investigaci\u00f3n de todo el arco Mediterr\u00e1neo, adem\u00e1s de Sud\u00e1frica, Australia, Chile o Argentina, que tambi\u00e9n tienen el mismo clima. Pero, de hecho, en Catalu\u00f1a y en el resto de Espa\u00f1a podemos sacar pecho porque probablemente somos quienes hacemos una investigaci\u00f3n m\u00e1s avanzada en gesti\u00f3n del agua, con la particularidad de que mucha de esta gesti\u00f3n es colectiva y p\u00fablica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Llegaste al IRTA hace m\u00e1s de dos d\u00e9cadas. \u00bfQu\u00e9 te trajo aqu\u00ed?<\/strong><br>Mi recorrido no es habitual. Despu\u00e9s de la carrera y el doctorado, no hice ning\u00fan postdoc, sino que trabaj\u00e9 cinco a\u00f1os como t\u00e9cnico en los campos experimentales de la Universidad de Barcelona. Esto me permiti\u00f3 formar parte de varios grupos de investigaci\u00f3n a la vez. Todos ten\u00edan en com\u00fan que hac\u00edan trabajo de campo y necesitaban tecnolog\u00edas para su investigaci\u00f3n: instrumentaci\u00f3n, simulaciones, sens\u00f3rica\u2026 Pues este, m\u00e1s que el agua, ha sido el hilo conductor de mi recorrido profesional. Podr\u00edamos decir que me he ido especializando en la digitalizaci\u00f3n en el campo. Y, en ese momento, acab\u00e9 trabajando en un tema sobre Chern\u00f3byl.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfNos lo cuentas?<\/strong><br>A finales de los noventa, se hac\u00edan muchos proyectos sobre c\u00f3mo solucionar los problemas de las zonas contaminadas por ese accidente nuclear, y sobre cu\u00e1l deber\u00eda ser el plan de contingencia si un accidente as\u00ed ocurriera en Europa occidental. Yo, concretamente, trabaj\u00e9 en dos proyectos europeos para estudiar c\u00f3mo los contaminantes pasaban del suelo a la ra\u00edz. Pues lo hicimos tan bien que el problema acab\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfDe qu\u00e9 forma?<\/strong><br>Parec\u00eda que ese accidente representar\u00eda un problema durante mucho tiempo, que las zonas afectadas de Ucrania y Bielorrusia quedar\u00edan contaminadas durante siglos. \u00a1Pues ahora estamos importando grano de esas zonas! Una de las conclusiones de esos proyectos fue que la situaci\u00f3n se hab\u00eda estabilizado mucho m\u00e1s r\u00e1pido de lo que pens\u00e1bamos. Los contaminantes quedaron enganchados a las arcillas del suelo y, aunque sigan all\u00ed, no pasan hacia los cultivos. \u00a1Fue una sorpresa positiva que nos dej\u00f3 sin trabajo! Tuve que reciclarme, y lo hice en el IRTA.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>(\u2026)<\/strong><br>Primero, me dediqu\u00e9 a la digitalizaci\u00f3n de la horticultura intensiva de la comarca del Maresme, pero en aquella \u00e9poca, los invernaderos se vend\u00edan para crecer urban\u00edsticamente, as\u00ed que el trabajo no ten\u00eda demasiado futuro. Y termin\u00e9 en L\u00e9rida, aqu\u00ed, en el <a href=\"https:\/\/www.irta.cat\/es\/centres\/fruitcentre\/\">Fruitcentre<\/a>, trabajando en temas de agua.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfQu\u00e9 es lo m\u00e1s gratificante de tu trabajo?<\/strong><br>Que no solo hacemos burbujas en una pecera, sino que jugamos con fuego real en una trinchera. Y eso, si te sale bien, es gratificante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfNos pones un ejemplo?<\/strong><br>En 2023, en el IRTA estuvimos en el ojo del hurac\u00e1n ante la crisis de la sequ\u00eda. Varios sectores se peleaban, y a nosotros nos situaron de mediador. En L\u00e9rida, el conflicto fue entre comunidades de regantes que se disputaban el mismo embalse, y en Gerona fue entre el abastecimiento urbano y el de la agricultura. Fueron dos batallas distintas en paralelo. Tuvimos la suerte de que la situaci\u00f3n se afloj\u00f3, pero realmente era inevitable que hubiera un mediador. Que nos situaran a nosotros en ese papel fue intenso, muy arriesgado, pero tambi\u00e9n muy motivador. Fue un reconocimiento.<\/p>\n\n\n\n<h3 class=\"wp-block-heading has-text-align-center\"><em>\u201cEn 2023, los agricultores y las comunidades de regantes no pod\u00edan creer que iban a quedarse sin agua. Es un tema de sostenibilidad ambiental y econ\u00f3mica\u201d<\/em><\/h3>\n\n\n\n<h2 class=\"wp-block-heading\"><\/h2>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfPodemos decir que ha habido un antes y un despu\u00e9s, en tu trabajo?<\/strong><br>S\u00ed. A principios de 2023, los agricultores y las comunidades de regantes no pod\u00edan creer que iban a quedarse sin agua. Dec\u00edan que nunca hab\u00eda pasado. Ahora s\u00ed lo creen: aquello pas\u00f3 y puede volver a ocurrir. Y no es un tema \u00fanicamente ambiental, sino de sostenibilidad econ\u00f3mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfC\u00f3mo te gustar\u00eda imaginarte el sector agr\u00edcola catal\u00e1n, de cara a 2030?<\/strong><br>Me gustar\u00eda que los agricultores est\u00e9n m\u00e1s empoderados. Que se sientan lo suficientemente valientes y con confianza en el futuro para hacer las inversiones que necesitan. Y, como dec\u00eda, para conseguirlo deben combinar la sostenibilidad econ\u00f3mica con la ambiental. Est\u00e1n haciendo esfuerzos y esta es la direcci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>\u00bfY con respecto al IRTA?<\/strong><br>Pues me gusta mucho estar rodeado de un equipo tan competente. Es de las cosas m\u00e1s gratificantes. Personas competentes y tambi\u00e9n muy implicadas en el sector. Esto no se encuentra en cualquier instituci\u00f3n y es uno de los aspectos m\u00e1s atractivos del IRTA.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><a href=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Equip-programa-Us-eficient-aigua-IRTA-scaled.jpg\" class=\"fancybox irta-lightbox-bridge\" data-fancybox=\"irta-images\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Equip-programa-Us-eficient-aigua-IRTA-1024x768.jpg\" alt=\"Bona part de l\u2019equip del programa d\u2019\u00das eficient de l\u2019aigua en l\u2019agricultura.\" class=\"wp-image-86797\" srcset=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Equip-programa-Us-eficient-aigua-IRTA-1024x768.jpg 1024w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Equip-programa-Us-eficient-aigua-IRTA-300x225.jpg 300w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Equip-programa-Us-eficient-aigua-IRTA-768x576.jpg 768w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Equip-programa-Us-eficient-aigua-IRTA-1536x1152.jpg 1536w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Equip-programa-Us-eficient-aigua-IRTA-2048x1536.jpg 2048w, https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Equip-programa-Us-eficient-aigua-IRTA-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">Buena parte del equipo del programa de Uso eficiente del agua en la agricultura, que Casades\u00fas lidera.<\/figcaption><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Hoy, \u00bfqu\u00e9 es lo que m\u00e1s te mueve como investigador?<\/strong><br>Creo que debemos ver el agua de forma integrativa, hol\u00edstica, en varias escalas al mismo tiempo. Parcelas individuales, fincas de comunidades de regantes, que si dan m\u00e1s agua a una parcela quiz\u00e1s deben dar menos a otra, y tambi\u00e9n a escala nacional. Un mismo embalse o acu\u00edfero suministra agua a mucha gente, y debemos mirarlo as\u00ed. El agua de una finca est\u00e1 relacionada con cu\u00e1nta fruta dejamos en el \u00e1rbol, qu\u00e9 tama\u00f1o de \u00e1rbol tenemos, qu\u00e9 variedades, y tambi\u00e9n est\u00e1 relacionada con lo que se est\u00e1 haciendo en el territorio. Creo que la gobernanza colectiva del agua es el camino.<\/p>\n","protected":false},"featured_media":86764,"template":"","categoria_noticia":[],"etiqueta_filtrar_noticia":[11311],"class_list":["post-86972","noticia","type-noticia","status-publish","has-post-thumbnail","hentry","etiqueta_filtrar_noticia-optimizacion-del-agua"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>\u201cEn el caso del agua en Catalu\u00f1a, la gobernanza colectiva es el camino\u201d<\/title>\r\n<meta name=\"description\" content=\"Entrevistamos al investigador Jaume Casades\u00fas, jefe del programa de Uso eficiente del agua en la agricultura del IRTA.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/\" \/>\r\n<meta property=\"og:locale\" content=\"es_ES\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"\u201cEn el caso del agua en Catalu\u00f1a, la gobernanza colectiva es el camino\u201d\" \/>\r\n<meta property=\"og:description\" content=\"Entrevistamos al investigador Jaume Casades\u00fas, jefe del programa de Uso eficiente del agua en la agricultura del IRTA.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/\" \/>\r\n<meta property=\"og:site_name\" content=\"IRTA\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/irtacat\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-03-27T12:54:02+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\r\n\t<meta property=\"og:image:height\" content=\"669\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@irtacat\" \/>\r\n<meta name=\"twitter:label1\" content=\"Tiempo de lectura\" \/>\n\t<meta name=\"twitter:data1\" content=\"16 minutos\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/noticia\\\/entrevista-jaume-casadesus-agua-cataluna\\\/\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/noticia\\\/entrevista-jaume-casadesus-agua-cataluna\\\/\",\"name\":\"\u201cEn el caso del agua en Catalu\u00f1a, la gobernanza colectiva es el camino\u201d\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/noticia\\\/entrevista-jaume-casadesus-agua-cataluna\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/noticia\\\/entrevista-jaume-casadesus-agua-cataluna\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Jaume-Casadesus-Fruitcentre.jpg\",\"datePublished\":\"2025-03-28T11:48:10+00:00\",\"dateModified\":\"2026-03-27T12:54:02+00:00\",\"description\":\"Entrevistamos al investigador Jaume Casades\u00fas, jefe del programa de Uso eficiente del agua en la agricultura del IRTA.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/noticia\\\/entrevista-jaume-casadesus-agua-cataluna\\\/#breadcrumb\"},\"inLanguage\":\"es\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.irta.cat\\\/es\\\/noticia\\\/entrevista-jaume-casadesus-agua-cataluna\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/noticia\\\/entrevista-jaume-casadesus-agua-cataluna\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Jaume-Casadesus-Fruitcentre.jpg\",\"contentUrl\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2025\\\/03\\\/Jaume-Casadesus-Fruitcentre.jpg\",\"width\":1000,\"height\":669,\"caption\":\"Jaume Casades\u00fas\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/noticia\\\/entrevista-jaume-casadesus-agua-cataluna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Jaume Casades\u00fas: \u201cEn el caso del agua en Catalu\u00f1a, la gobernanza colectiva es el camino\u201d\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/#website\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/\",\"name\":\"IRTA\",\"description\":\"Institut de Recerca i Tecnologia Agroaliment\u00e0ries\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/#organization\"},\"alternateName\":\"%%sitename%% %%sep%% %%title%%\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"es\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/#organization\",\"name\":\"IRTA\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"es\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-IRTA-verm.png\",\"contentUrl\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-IRTA-verm.png\",\"width\":1250,\"height\":500,\"caption\":\"IRTA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/es\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/irtacat\",\"https:\\\/\\\/x.com\\\/irtacat\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cEn el caso del agua en Catalu\u00f1a, la gobernanza colectiva es el camino\u201d","description":"Entrevistamos al investigador Jaume Casades\u00fas, jefe del programa de Uso eficiente del agua en la agricultura del IRTA.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/","og_locale":"es_ES","og_type":"article","og_title":"\u201cEn el caso del agua en Catalu\u00f1a, la gobernanza colectiva es el camino\u201d","og_description":"Entrevistamos al investigador Jaume Casades\u00fas, jefe del programa de Uso eficiente del agua en la agricultura del IRTA.","og_url":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/","og_site_name":"IRTA","article_publisher":"https:\/\/www.facebook.com\/irtacat","article_modified_time":"2026-03-27T12:54:02+00:00","og_image":[{"width":1000,"height":669,"url":"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@irtacat","twitter_misc":{"Tiempo de lectura":"16 minutos"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/","url":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/","name":"\u201cEn el caso del agua en Catalu\u00f1a, la gobernanza colectiva es el camino\u201d","isPartOf":{"@id":"https:\/\/www.irta.cat\/es\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/#primaryimage"},"image":{"@id":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre.jpg","datePublished":"2025-03-28T11:48:10+00:00","dateModified":"2026-03-27T12:54:02+00:00","description":"Entrevistamos al investigador Jaume Casades\u00fas, jefe del programa de Uso eficiente del agua en la agricultura del IRTA.","breadcrumb":{"@id":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/#breadcrumb"},"inLanguage":"es","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/"]}]},{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/#primaryimage","url":"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre.jpg","contentUrl":"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/03\/Jaume-Casadesus-Fruitcentre.jpg","width":1000,"height":669,"caption":"Jaume Casades\u00fas"},{"@type":"BreadcrumbList","@id":"https:\/\/www.irta.cat\/es\/noticia\/entrevista-jaume-casadesus-agua-cataluna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.irta.cat\/es\/"},{"@type":"ListItem","position":2,"name":"Jaume Casades\u00fas: \u201cEn el caso del agua en Catalu\u00f1a, la gobernanza colectiva es el camino\u201d"}]},{"@type":"WebSite","@id":"https:\/\/www.irta.cat\/es\/#website","url":"https:\/\/www.irta.cat\/es\/","name":"IRTA","description":"Institut de Recerca i Tecnologia Agroaliment\u00e0ries","publisher":{"@id":"https:\/\/www.irta.cat\/es\/#organization"},"alternateName":"%%sitename%% %%sep%% %%title%%","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irta.cat\/es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"es"},{"@type":"Organization","@id":"https:\/\/www.irta.cat\/es\/#organization","name":"IRTA","url":"https:\/\/www.irta.cat\/es\/","logo":{"@type":"ImageObject","inLanguage":"es","@id":"https:\/\/www.irta.cat\/es\/#\/schema\/logo\/image\/","url":"https:\/\/www.irta.cat\/wp-content\/uploads\/2023\/04\/Logo-IRTA-verm.png","contentUrl":"https:\/\/www.irta.cat\/wp-content\/uploads\/2023\/04\/Logo-IRTA-verm.png","width":1250,"height":500,"caption":"IRTA"},"image":{"@id":"https:\/\/www.irta.cat\/es\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/irtacat","https:\/\/x.com\/irtacat"]}]}},"_links":{"self":[{"href":"https:\/\/www.irta.cat\/es\/wp-json\/wp\/v2\/noticia\/86972","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irta.cat\/es\/wp-json\/wp\/v2\/noticia"}],"about":[{"href":"https:\/\/www.irta.cat\/es\/wp-json\/wp\/v2\/types\/noticia"}],"version-history":[{"count":10,"href":"https:\/\/www.irta.cat\/es\/wp-json\/wp\/v2\/noticia\/86972\/revisions"}],"predecessor-version":[{"id":87056,"href":"https:\/\/www.irta.cat\/es\/wp-json\/wp\/v2\/noticia\/86972\/revisions\/87056"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irta.cat\/es\/wp-json\/wp\/v2\/media\/86764"}],"wp:attachment":[{"href":"https:\/\/www.irta.cat\/es\/wp-json\/wp\/v2\/media?parent=86972"}],"wp:term":[{"taxonomy":"categoria_noticia","embeddable":true,"href":"https:\/\/www.irta.cat\/es\/wp-json\/wp\/v2\/categoria_noticia?post=86972"},{"taxonomy":"etiqueta_filtrar_noticia","embeddable":true,"href":"https:\/\/www.irta.cat\/es\/wp-json\/wp\/v2\/etiqueta_filtrar_noticia?post=86972"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}