{"id":1491,"date":"2023-01-19T07:53:13","date_gmt":"2023-01-19T07:53:13","guid":{"rendered":"https:\/\/www.irta.cat\/personal\/laura-beltran-garcia\/"},"modified":"2024-11-18T23:06:06","modified_gmt":"2024-11-18T22:06:06","slug":"laura-beltran-garcia","status":"publish","type":"personal","link":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/","title":{"rendered":"Laura Beltran Garcia"},"content":{"rendered":"","protected":false},"featured_media":82136,"parent":0,"template":"","tipus_de_treballador":[10953],"class_list":["post-1491","personal","type-personal","status-publish","has-post-thumbnail","hentry","tipus_de_treballador-support-staff"],"acf":{"nom_complet":"Beltr\u00e1n Garcia, Laura","codi_empleat":"8578","codi_departament":"Z1","centre":"30","carrec":"","lloc_tipus":"#N\/D","correu_electronic":"laura.beltrang@irta.cat","telefon":"93 467 40 40","extensio":"","telefon_mobil":"","data_inici":"20200901","data_fi":"99990909","informacio_professional":"","curriculum_vitae":null,"linkedin":"","twitter":"","recerca":"","researchgate":"","categoria":"Personal Suport","lastupdate":null,"dni":"","imarina":{"id_personal":"","id_entity":"","entity_parent":"","research_id":"","researchgate_id":"","academiaedu_id":"","publons":"","orcid":"","author_id":"","googlescholar_id":"","dialnet_id":""}},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v26.6 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\r\n<title>Laura Beltran Garcia &#187; IRTA<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Laura Beltran Garcia &#187; IRTA\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/\" \/>\r\n<meta property=\"og:site_name\" content=\"IRTA\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/irtacat\" \/>\r\n<meta property=\"article:modified_time\" content=\"2024-11-18T22:06:06+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/02\/Logo-IRTA-verm.png\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1250\" \/>\r\n\t<meta property=\"og:image:height\" content=\"500\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/png\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@irtacat\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/\",\"url\":\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/\",\"name\":\"Laura Beltran Garcia &#187; IRTA\",\"isPartOf\":{\"@id\":\"https:\/\/www.irta.cat\/en\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/www.irta.cat\/wp-content\/uploads\/personal-thumbnails\/8578.jpg\",\"datePublished\":\"2023-01-19T07:53:13+00:00\",\"dateModified\":\"2024-11-18T22:06:06+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#primaryimage\",\"url\":\"https:\/\/www.irta.cat\/wp-content\/uploads\/personal-thumbnails\/8578.jpg\",\"contentUrl\":\"https:\/\/www.irta.cat\/wp-content\/uploads\/personal-thumbnails\/8578.jpg\",\"width\":1000,\"height\":1000},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\/\/www.irta.cat\/en\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Laura Beltran Garcia\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.irta.cat\/en\/#website\",\"url\":\"https:\/\/www.irta.cat\/en\/\",\"name\":\"IRTA\",\"description\":\"Institut de Recerca i Tecnologia Agroaliment\u00e0ries\",\"publisher\":{\"@id\":\"https:\/\/www.irta.cat\/en\/#organization\"},\"alternateName\":\"%%sitename%% %%sep%% %%title%%\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.irta.cat\/en\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.irta.cat\/en\/#organization\",\"name\":\"IRTA\",\"url\":\"https:\/\/www.irta.cat\/en\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\/\/www.irta.cat\/en\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.irta.cat\/wp-content\/uploads\/2023\/04\/Logo-IRTA-verm.png\",\"contentUrl\":\"https:\/\/www.irta.cat\/wp-content\/uploads\/2023\/04\/Logo-IRTA-verm.png\",\"width\":1250,\"height\":500,\"caption\":\"IRTA\"},\"image\":{\"@id\":\"https:\/\/www.irta.cat\/en\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/irtacat\",\"https:\/\/x.com\/irtacat\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Laura Beltran Garcia &#187; IRTA","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/","og_locale":"en_US","og_type":"article","og_title":"Laura Beltran Garcia &#187; IRTA","og_url":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/","og_site_name":"IRTA","article_publisher":"https:\/\/www.facebook.com\/irtacat","article_modified_time":"2024-11-18T22:06:06+00:00","og_image":[{"width":1250,"height":500,"url":"https:\/\/www.irta.cat\/wp-content\/uploads\/2025\/02\/Logo-IRTA-verm.png","type":"image\/png"}],"twitter_card":"summary_large_image","twitter_site":"@irtacat","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/","url":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/","name":"Laura Beltran Garcia &#187; IRTA","isPartOf":{"@id":"https:\/\/www.irta.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#primaryimage"},"image":{"@id":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irta.cat\/wp-content\/uploads\/personal-thumbnails\/8578.jpg","datePublished":"2023-01-19T07:53:13+00:00","dateModified":"2024-11-18T22:06:06+00:00","breadcrumb":{"@id":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#primaryimage","url":"https:\/\/www.irta.cat\/wp-content\/uploads\/personal-thumbnails\/8578.jpg","contentUrl":"https:\/\/www.irta.cat\/wp-content\/uploads\/personal-thumbnails\/8578.jpg","width":1000,"height":1000},{"@type":"BreadcrumbList","@id":"https:\/\/www.irta.cat\/en\/personal\/laura-beltran-garcia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.irta.cat\/en\/"},{"@type":"ListItem","position":2,"name":"Laura Beltran Garcia"}]},{"@type":"WebSite","@id":"https:\/\/www.irta.cat\/en\/#website","url":"https:\/\/www.irta.cat\/en\/","name":"IRTA","description":"Institut de Recerca i Tecnologia Agroaliment\u00e0ries","publisher":{"@id":"https:\/\/www.irta.cat\/en\/#organization"},"alternateName":"%%sitename%% %%sep%% %%title%%","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irta.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.irta.cat\/en\/#organization","name":"IRTA","url":"https:\/\/www.irta.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.irta.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.irta.cat\/wp-content\/uploads\/2023\/04\/Logo-IRTA-verm.png","contentUrl":"https:\/\/www.irta.cat\/wp-content\/uploads\/2023\/04\/Logo-IRTA-verm.png","width":1250,"height":500,"caption":"IRTA"},"image":{"@id":"https:\/\/www.irta.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/irtacat","https:\/\/x.com\/irtacat"]}]}},"_links":{"self":[{"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/personal\/1491","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/personal"}],"about":[{"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/types\/personal"}],"version-history":[{"count":0,"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/personal\/1491\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/media\/82136"}],"wp:attachment":[{"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/media?parent=1491"}],"wp:term":[{"taxonomy":"tipus_de_treballador","embeddable":true,"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/tipus_de_treballador?post=1491"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}