{"id":131809,"date":"2026-03-05T15:11:27","date_gmt":"2026-03-05T14:11:27","guid":{"rendered":"https:\/\/www.irta.cat\/plantes-experimentals-biogas\/"},"modified":"2026-04-27T10:18:13","modified_gmt":"2026-04-27T08:18:13","slug":"experimental-biogas-plants","status":"publish","type":"page","link":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/","title":{"rendered":"IRTA\u2019s experimental biogas plants"},"content":{"rendered":"\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:90%\">\n<h1 class=\"wp-block-heading\" style=\"font-size:42px\"><strong>IRTA\u2019s experimental biogas plants<\/strong><\/h1>\n\n\n\n<p class=\"wp-block-paragraph\" style=\"font-size:24px\"><strong>For self-consumption on small or medium-sized farms<\/strong><\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-full\"><a href=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg\" class=\"fancybox irta-lightbox-bridge\" data-fancybox=\"irta-images\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"865\" src=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg\" alt=\"\" class=\"wp-image-130358\" srcset=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg 1920w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-300x135.jpg 300w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-1024x461.jpg 1024w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-768x346.jpg 768w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-1536x692.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/a><figcaption class=\"wp-element-caption\">The experimental biogas plant at Mas Bov\u00e9, in the final stage of construction.<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"wp-block-paragraph\">As part of the <a href=\"https:\/\/www.irta.cat\/en\/centres\/irta-mas-bove\/\" target=\"_blank\" rel=\"noreferrer noopener\">2024\u20132027 Strategic Plan<\/a>, one of our strategic scientific objectives is <strong><a href=\"https:\/\/www.irta.cat\/en\/bioeconomy-circular-waste-by-products-biogas\/\" target=\"_blank\" rel=\"noreferrer noopener\">to promote the bioeconomy in order to reduce the agri-food sector\u2019s environmental impact<\/a><\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">In this context, we are building <strong>two biogas plants<\/strong>.<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>One at the<a href=\"https:\/\/www.irta.cat\/en\/centres\/evam\/\" target=\"_blank\" rel=\"noreferrer noopener\"> cattle farm in Monells<\/a> (Girona), where there are dairy cows.<\/li>\n\n\n\n<li>And another at the <a href=\"https:\/\/www.irta.cat\/en\/centres\/irta-mas-bove\/\" target=\"_blank\" rel=\"noreferrer noopener\">Mas Bov\u00e9<\/a> farm (Tarragona), where there are pigs and chickens.<\/li>\n<\/ul>\n\n\n\n<p class=\"wp-block-paragraph\">This infographic summarises how they will work:<\/p>\n\n\n<div class=\"wp-block-image\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a97dc8a8178b&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a97dc8a8178b\" class=\"aligncenter size-full wp-lightbox-container\"><a href=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/04\/BIOGAS_ENG_DESKTOP-scaled.jpg\" class=\"fancybox irta-lightbox-bridge\" data-fancybox=\"irta-images\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"1310\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" src=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/04\/BIOGAS_ENG_DESKTOP-scaled.jpg\" alt=\"\" class=\"wp-image-136499\" srcset=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/04\/BIOGAS_ENG_DESKTOP-scaled.jpg 1920w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/04\/BIOGAS_ENG_DESKTOP-300x205.jpg 300w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/04\/BIOGAS_ENG_DESKTOP-1024x699.jpg 1024w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/04\/BIOGAS_ENG_DESKTOP-768x524.jpg 768w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/04\/BIOGAS_ENG_DESKTOP-1536x1048.jpg 1536w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/04\/BIOGAS_ENG_DESKTOP-2048x1397.jpg 2048w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/a><\/figure>\n<\/div>\n\n\n<p class=\"wp-block-paragraph\">So, on both farms:<\/p>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>We will convert manure into biogas<\/strong><\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">Through a <strong>digestion process<\/strong> carried out by anaerobic microorganisms: bacteria and archaea that work without oxygen inside a tank.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">The technologies we will use on each farm will be different.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>We will use the biog\u00e0s<\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>For<strong>heating<\/strong> (in the sow maternity unit at Mas Bov\u00e9).<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>And for <strong>heating cleaning water<\/strong> (to disinfect the milking parlour for the cows at Monells).<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>We will make use of the remaining organic matter<\/strong><\/h6>\n\n\n\n<p class=\"wp-block-paragraph\">It is called <strong>digestate<\/strong>, and we will separate it into two fractions:<\/p>\n\n\n\n<ul class=\"wp-block-list\">\n<li>The solid part will be converted into <strong>high-quality organic fertiliser (compost)<\/strong> thanks to the work of aerobic bacteria and fungi.<br><br><\/li>\n\n\n\n<li>And the liquid part will be converted into <strong>water for irrigation<\/strong> (on the fields at Monells) <strong>and for cleaning<\/strong> (on the farms at Mas Bov\u00e9).<\/li>\n<\/ul>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h6 class=\"wp-block-heading\"><strong>All of this will enable us to:<\/strong><\/h6>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Make our farms <strong>more self-sufficient and sustainable<\/strong>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>Collaborate with companies or projects wishing to <strong>test new technologies<\/strong>.<\/li>\n<\/ul>\n\n\n\n<ul class=\"wp-block-list\">\n<li>And <strong>demonstrate to the sector how these biogas plants operate and the results they achieve<\/strong>.<\/li>\n<\/ul>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n<div class=\"wp-block-image\">\n<figure class=\"aligncenter size-large\"><a href=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/biogas-mas-bove-en-construccio-scaled.jpg\" class=\"fancybox irta-lightbox-bridge\" data-fancybox=\"irta-images\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"768\" src=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/biogas-mas-bove-en-construccio-1024x768.jpg\" alt=\"\" class=\"wp-image-130244\" srcset=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/biogas-mas-bove-en-construccio-1024x768.jpg 1024w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/biogas-mas-bove-en-construccio-300x225.jpg 300w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/biogas-mas-bove-en-construccio-768x576.jpg 768w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/biogas-mas-bove-en-construccio-1536x1152.jpg 1536w, https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/biogas-mas-bove-en-construccio-scaled.jpg 1920w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><figcaption class=\"wp-element-caption\">The Mas Bov\u00e9 biogas plant, at the start of construction.<\/figcaption><\/figure>\n<\/div>\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<h5 class=\"wp-block-heading\">Find out about IRTA\u2019s strategic scientific objective relating to the bioeconomy:<\/h5>\n\n\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-8f761849 wp-block-columns-is-layout-flex\" style=\"background-color:#fff2e6\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:100%\">\r\n    <!-- block: block-cita-personal -->\r\n    <section  data-block_id=\"block_9341169bb07f76678e45ae3ac381187c\" class=\"cita-perfil-div cita-perfil-gutenberg \">\r\n        <div class=\"row\">\r\n            <div class=\"cita-conainer\">\r\n                                    <div class=\"cita-text\">\r\n                        <blockquote class=\"wp-block-quote\">We want to help transform the technologies and practices of farmers and livestock breeders to maximise the environmental and economic sustainability of their activities.<\/blockquote>\r\n                    <\/div>\r\n                \r\n                                    <a href=\"https:\/\/www.irta.cat\/en\/personal\/ma-belen-fernandez-garcia\/\" target=\"_self\">\r\n                                        <div class=\"cita-perfil\">\r\n                        <div class=\"img-perfil\">\r\n                            <img decoding=\"async\" src=\"https:\/\/www.irta.cat\/wp-content\/uploads\/personal-thumbnails\/4015.jpg\" alt=\"Ma. belen Fernandez Garcia\" title=\"Ma. belen Fernandez Garcia\" loading=\"lazy\">\r\n                        <\/div>\r\n                        <div class=\"info-perfil\">\r\n                            <h2>Fern\u00e1ndez Garcia, Bel\u00e9n<\/h2>\r\n                                                            <p>Environmental Biotechnology researcher<\/p>\r\n                                                    <\/div>\r\n                    <\/div>\r\n                                        <\/a>\r\n                            <\/div>\r\n        <\/div>\r\n    <\/section>\r\n    <!-- block: block-cita-personal -->\r\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<div class=\"wp-block-buttons has-custom-font-size layout-center has-medium-font-size is-horizontal is-content-justification-right is-nowrap is-layout-flex wp-container-core-buttons-is-layout-1840c821 wp-block-buttons-is-layout-flex\">\n<div class=\"wp-block-button has-custom-width wp-block-button__width-75 is-style-fill center-btn\"><a class=\"wp-block-button__link has-background has-large-font-size has-text-align-center has-custom-font-size wp-element-button\" href=\"https:\/\/www.irta.cat\/en\/bioeconomy-circular-waste-by-products-biogas\/\" style=\"background-color:#ce003a\" target=\"_blank\" rel=\"noreferrer noopener\"><strong>This is how we are boosting the bioeconomy in the agri-food sector<\/strong><\/a><\/div>\n<\/div>\n\n\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n\n\n<p class=\"wp-block-paragraph\"><\/p>\n","protected":false},"excerpt":{"rendered":"<p>IRTA\u2019s experimental biogas plants For self-consumption on small or medium-sized farms As part of the 2024\u20132027 Strategic Plan, one of our strategic scientific objectives is to promote the bioeconomy in order to reduce the agri-food sector\u2019s environmental impact. In this context, we are building two biogas plants. This infographic summarises how they will work: So, [&hellip;]<\/p>\n","protected":false},"author":4,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"page-templates\/gutenberg.php","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-131809","page","type-page","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.2 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>IRTA\u2019s experimental biogas plants &#187; IRTA<\/title>\r\n<meta name=\"description\" content=\"IRTA\u2019s experimental biogas plants For self-consumption on small or medium-sized farms The experimental biogas plant at Mas Bov\u00e9, in the final stage of Learn how IRTA\u2019s two experimental biogas plants work. They are located in Catalonia, Spain.\" \/>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"IRTA\u2019s experimental biogas plants &#187; IRTA\" \/>\r\n<meta property=\"og:description\" content=\"IRTA\u2019s experimental biogas plants For self-consumption on small or medium-sized farms The experimental biogas plant at Mas Bov\u00e9, in the final stage of Learn how IRTA\u2019s two experimental biogas plants work. They are located in Catalonia, Spain.\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/\" \/>\r\n<meta property=\"og:site_name\" content=\"IRTA\" \/>\r\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/irtacat\" \/>\r\n<meta property=\"article:modified_time\" content=\"2026-04-27T08:18:13+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\r\n\t<meta property=\"og:image:height\" content=\"865\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:site\" content=\"@irtacat\" \/>\r\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"3 minutes\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/experimental-biogas-plants\\\/\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/experimental-biogas-plants\\\/\",\"name\":\"IRTA\u2019s experimental biogas plants &#187; IRTA\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/experimental-biogas-plants\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/experimental-biogas-plants\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg\",\"datePublished\":\"2026-03-05T14:11:27+00:00\",\"dateModified\":\"2026-04-27T08:18:13+00:00\",\"description\":\"IRTA\u2019s experimental biogas plants For self-consumption on small or medium-sized farms The experimental biogas plant at Mas Bov\u00e9, in the final stage of Learn how IRTA\u2019s two experimental biogas plants work. They are located in Catalonia, Spain.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/experimental-biogas-plants\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.irta.cat\\\/en\\\/experimental-biogas-plants\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/experimental-biogas-plants\\\/#primaryimage\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/experimental-biogas-plants\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Inici\",\"item\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"IRTA\u2019s experimental biogas plants\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/\",\"name\":\"IRTA\",\"description\":\"Institut de Recerca i Tecnologia Agroaliment\u00e0ries\",\"publisher\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/#organization\"},\"alternateName\":\"%%sitename%% %%sep%% %%title%%\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/#organization\",\"name\":\"IRTA\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-IRTA-verm.png\",\"contentUrl\":\"https:\\\/\\\/www.irta.cat\\\/wp-content\\\/uploads\\\/2023\\\/04\\\/Logo-IRTA-verm.png\",\"width\":1250,\"height\":500,\"caption\":\"IRTA\"},\"image\":{\"@id\":\"https:\\\/\\\/www.irta.cat\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/irtacat\",\"https:\\\/\\\/x.com\\\/irtacat\"]}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"IRTA\u2019s experimental biogas plants &#187; IRTA","description":"IRTA\u2019s experimental biogas plants For self-consumption on small or medium-sized farms The experimental biogas plant at Mas Bov\u00e9, in the final stage of Learn how IRTA\u2019s two experimental biogas plants work. They are located in Catalonia, Spain.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/","og_locale":"en_US","og_type":"article","og_title":"IRTA\u2019s experimental biogas plants &#187; IRTA","og_description":"IRTA\u2019s experimental biogas plants For self-consumption on small or medium-sized farms The experimental biogas plant at Mas Bov\u00e9, in the final stage of Learn how IRTA\u2019s two experimental biogas plants work. They are located in Catalonia, Spain.","og_url":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/","og_site_name":"IRTA","article_publisher":"https:\/\/www.facebook.com\/irtacat","article_modified_time":"2026-04-27T08:18:13+00:00","og_image":[{"width":1920,"height":865,"url":"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@irtacat","twitter_misc":{"Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/","url":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/","name":"IRTA\u2019s experimental biogas plants &#187; IRTA","isPartOf":{"@id":"https:\/\/www.irta.cat\/en\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/#primaryimage"},"image":{"@id":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/#primaryimage"},"thumbnailUrl":"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg","datePublished":"2026-03-05T14:11:27+00:00","dateModified":"2026-04-27T08:18:13+00:00","description":"IRTA\u2019s experimental biogas plants For self-consumption on small or medium-sized farms The experimental biogas plant at Mas Bov\u00e9, in the final stage of Learn how IRTA\u2019s two experimental biogas plants work. They are located in Catalonia, Spain.","breadcrumb":{"@id":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/#primaryimage","url":"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg","contentUrl":"https:\/\/www.irta.cat\/wp-content\/uploads\/2026\/03\/plata-experimental-biogas-mas-bove-IRTA-fase-final-construccio-scaled.jpg"},{"@type":"BreadcrumbList","@id":"https:\/\/www.irta.cat\/en\/experimental-biogas-plants\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Inici","item":"https:\/\/www.irta.cat\/en\/"},{"@type":"ListItem","position":2,"name":"IRTA\u2019s experimental biogas plants"}]},{"@type":"WebSite","@id":"https:\/\/www.irta.cat\/en\/#website","url":"https:\/\/www.irta.cat\/en\/","name":"IRTA","description":"Institut de Recerca i Tecnologia Agroaliment\u00e0ries","publisher":{"@id":"https:\/\/www.irta.cat\/en\/#organization"},"alternateName":"%%sitename%% %%sep%% %%title%%","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.irta.cat\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/www.irta.cat\/en\/#organization","name":"IRTA","url":"https:\/\/www.irta.cat\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.irta.cat\/en\/#\/schema\/logo\/image\/","url":"https:\/\/www.irta.cat\/wp-content\/uploads\/2023\/04\/Logo-IRTA-verm.png","contentUrl":"https:\/\/www.irta.cat\/wp-content\/uploads\/2023\/04\/Logo-IRTA-verm.png","width":1250,"height":500,"caption":"IRTA"},"image":{"@id":"https:\/\/www.irta.cat\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/irtacat","https:\/\/x.com\/irtacat"]}]}},"_links":{"self":[{"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/pages\/131809","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/comments?post=131809"}],"version-history":[{"count":13,"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/pages\/131809\/revisions"}],"predecessor-version":[{"id":138252,"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/pages\/131809\/revisions\/138252"}],"wp:attachment":[{"href":"https:\/\/www.irta.cat\/en\/wp-json\/wp\/v2\/media?parent=131809"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}